{"id":160,"date":"2008-01-01T00:01:18","date_gmt":"2007-12-31T23:01:18","guid":{"rendered":"http:\/\/sjvalderas.wordpress.com\/2008\/01\/01\/%c2%a1%c2%a1feliz-2008\/"},"modified":"2008-01-01T00:01:18","modified_gmt":"2007-12-31T23:01:18","slug":"feliz-2008","status":"publish","type":"post","link":"https:\/\/blogs.adosclicks.net\/myp\/2008\/01\/01\/feliz-2008\/","title":{"rendered":"\u00a1\u00a1Feliz 2008!!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/tbn0.google.com\/images?q=tbn:yFq0Ywzya68aZM:http:\/\/www.tuparada.com\/cardsimages\/633207819443232500.jpg\" alt=\"Tarjeta de Navidad felicitando el a\u00f1o 2008\" hspace=\"8\" vspace=\"8\" width=\"92\" height=\"63\" align=\"left\" \/>Un nuevo a\u00f1o, una nueva oportunidad para renovar nuestros proyectos, para cumplir los deseos a\u00fan no cumplidos&#8230;<\/p>\n<p>Deseamos que este a\u00f1o nuevo podamos seguir ayud\u00e1ndoos con nuestro\/vuestro blog, y esperamos tambi\u00e9n, que aport\u00e9is ideas para mejorarlo.<\/p>\n<p align=\"center\"><strong>\u00a1\u00a1\u00a1MUCHAS FELICIDADES!!! <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuevo a\u00f1o, una nueva oportunidad para renovar nuestros proyectos, para cumplir los deseos a\u00fan no cumplidos&#8230; Deseamos que este a\u00f1o nuevo podamos seguir ayud\u00e1ndoos con nuestro\/vuestro blog, y esperamos tambi\u00e9n, que aport\u00e9is ideas para mejorarlo. \u00a1\u00a1\u00a1MUCHAS FELICIDADES!!!<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4139],"tags":[],"class_list":["post-160","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/blogs.adosclicks.net\/myp\/wp-json\/wp\/v2\/posts\/160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.adosclicks.net\/myp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.adosclicks.net\/myp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.adosclicks.net\/myp\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.adosclicks.net\/myp\/wp-json\/wp\/v2\/comments?post=160"}],"version-history":[{"count":0,"href":"https:\/\/blogs.adosclicks.net\/myp\/wp-json\/wp\/v2\/posts\/160\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.adosclicks.net\/myp\/wp-json\/wp\/v2\/media?parent=160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.adosclicks.net\/myp\/wp-json\/wp\/v2\/categories?post=160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.adosclicks.net\/myp\/wp-json\/wp\/v2\/tags?post=160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}